{"id":10573,"date":"2024-03-03T12:19:05","date_gmt":"2024-03-03T17:19:05","guid":{"rendered":"https:\/\/www.conexioncesar.com\/?p=10573"},"modified":"2024-03-03T12:19:09","modified_gmt":"2024-03-03T17:19:09","slug":"la-unidad-de-busqueda-presenta-el-listado-digital-de-personas-dadas-por-desaparecidas","status":"publish","type":"post","link":"https:\/\/conexioncesar.com\/index.php\/2024\/03\/03\/la-unidad-de-busqueda-presenta-el-listado-digital-de-personas-dadas-por-desaparecidas\/","title":{"rendered":"La Unidad de B\u00fasqueda presenta el listado digital de personas dadas por desaparecidas"},"content":{"rendered":"\n<p>El conflicto armado en Colombia ha dejado a m\u00e1s de 104.000 personas desaparecidas. Este dato, construido por la Unidad de B\u00fasqueda de Personas dadas por Desaparecidas (UBPD), representa a miles y miles de hijos, hijas, padres, madres, hermanos, hermanas y otros familiares que siguen ausentes. Se trata de historias y recuerdos que mantienen viva la esperanza de las personas que les buscan.<\/p>\n\n\n\n<p>Como un aporte a la b\u00fasqueda humanitaria y extrajudicial, la UBPD presenta un listado digital con los nombres y los apellidos de las v\u00edctimas de este flagelo. Una herramienta tecnol\u00f3gica al servicio de las familias y personas buscadoras y sus organizaciones.<\/p>\n\n\n\n<p>Cada una de las p\u00e1ginas de este listado contiene 1.000 nombres, apellidos e historias. Los datos fueron recolectados por la Unidad de B\u00fasqueda tras revisar y recibir informaci\u00f3n de diferentes fuentes como entidades judiciales y administrativas del Estado colombiano, Fuerzas Militares, organizaciones civiles y de v\u00edctimas, instituciones acad\u00e9micas, aportantes colectivos e individuales de informaci\u00f3n, familiares buscadores, entre otras. M\u00e1s que una dolorosa estad\u00edstica, las personas que componen el listado merecen un lugar m\u00e1s visible dentro de la sociedad colombiana para que no queden en el olvido.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.conexioncesar.com\/wp-content\/uploads\/2024\/03\/C759F8FD-E456-43EA-88C6-0A0D1DD5E5DD-1024x768.jpeg\" alt=\"\" class=\"wp-image-10574\" style=\"width:390px;height:auto\" srcset=\"https:\/\/conexioncesar.com\/wp-content\/uploads\/2024\/03\/C759F8FD-E456-43EA-88C6-0A0D1DD5E5DD-1024x768.jpeg 1024w, https:\/\/conexioncesar.com\/wp-content\/uploads\/2024\/03\/C759F8FD-E456-43EA-88C6-0A0D1DD5E5DD-300x225.jpeg 300w, https:\/\/conexioncesar.com\/wp-content\/uploads\/2024\/03\/C759F8FD-E456-43EA-88C6-0A0D1DD5E5DD-768x576.jpeg 768w, https:\/\/conexioncesar.com\/wp-content\/uploads\/2024\/03\/C759F8FD-E456-43EA-88C6-0A0D1DD5E5DD.jpeg 1152w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto de referencia <\/figcaption><\/figure>\n\n\n\n<p>Este listado se alimenta de la informaci\u00f3n del universo de personas dadas por desaparecidas, un registro que elabora la UBPD a partir de diversas fuentes de datos. Ambas plataformas se encuentran en permanente actualizaci\u00f3n.<\/p>\n\n\n\n<p>Gabriel Burbano, director del \u00e1rea de Participaci\u00f3n, Contacto con las v\u00edctimas y Enfoques diferenciales de la UBPD, asegur\u00f3 que la disponibilidad de esta informaci\u00f3n es un ejercicio de memoria y reparaci\u00f3n para las miles y miles de personas que siguen ausentes por el conflicto armado.<\/p>\n\n\n\n<p>\u201cEs importante que, como sociedad, nos unamos a consultar esta base de datos porque seguramente les conocemos. Queremos dejar el mensaje de que les estamos buscando como un ejercicio de corresponsabilidad\u201d, indica Burbano.<\/p>\n\n\n\n<p>Cabe aclarar que esta herramienta se encuentra en constante verificaci\u00f3n y contrastaci\u00f3n de los datos. Si encuentran alguna inconsistencia o desean aportar nueva informaci\u00f3n, se pueden comunicar con la UBPD al siguiente correo para atenderles:<a href=\"mailto:servicioalciudadano@ubpdbusquedadesaparecidos.co\">servicioalciudadano@ubpdbusquedadesaparecidos.co<\/a><\/p>\n\n\n\n<p>La escritura de los nombres y apellidos de las personas que conforman la lista est\u00e1n transcritos de las bases de datos de las instituciones y organizaciones en las que se registr\u00f3 la desaparici\u00f3n desde los principios de presunci\u00f3n y legalidad por las fuentes primarias. La UBPD respeta la ortograf\u00eda de estos datos registrados por parte de las fuentes productoras de la informaci\u00f3n y la escritura correcta (u original) ser\u00e1 verificada por la autoridad competente para garantizar la plena identidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El conflicto armado en Colombia ha dejado a m\u00e1s de 104.000 personas desaparecidas. Este dato, construido por la Unidad de B\u00fasqueda de Personas dadas por Desaparecidas (UBPD), representa a miles y miles de hijos, hijas, padres, madres, hermanos, hermanas y otros familiares que siguen ausentes. Se trata de historias y recuerdos que mantienen viva la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10575,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-10573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-generales"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/conexioncesar.com\/wp-content\/uploads\/2024\/03\/9A1BBA82-08D1-4216-B432-5B6C20233257.jpeg","_links":{"self":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/10573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/comments?post=10573"}],"version-history":[{"count":1,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/10573\/revisions"}],"predecessor-version":[{"id":10576,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/10573\/revisions\/10576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/media\/10575"}],"wp:attachment":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/media?parent=10573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/categories?post=10573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/tags?post=10573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}