{"id":16700,"date":"2025-10-27T01:50:39","date_gmt":"2025-10-27T06:50:39","guid":{"rendered":"https:\/\/conexioncesar.com\/?p=16700"},"modified":"2025-10-27T01:50:41","modified_gmt":"2025-10-27T06:50:41","slug":"con-28-mil-votos-alexandra-pineda-obtuvo-triunfo-inobjetable-revalidando-el-liderazgo-politico","status":"publish","type":"post","link":"https:\/\/conexioncesar.com\/index.php\/2025\/10\/27\/con-28-mil-votos-alexandra-pineda-obtuvo-triunfo-inobjetable-revalidando-el-liderazgo-politico\/","title":{"rendered":"Con 28 mil votos, Alexandra Pineda obtuvo triunfo inobjetable, revalidando el liderazgo pol\u00edtico\u00a0"},"content":{"rendered":"\n<p>Una victoria inobjetable se llev\u00f3 la precandidata progresista Alexandra Pineda Ortiz al lograr 28 mil votos en la consulta interna del Pacto Hist\u00f3rico que convoc\u00f3 al pueblo para escoger a quienes los representar\u00e1n en las elecciones del pr\u00f3ximo a\u00f1o.<\/p>\n\n\n\n<p>El triunfo se da en medio de reclamaciones m\u00e1s que v\u00e1lidas a la organizaci\u00f3n electoral que quit\u00f3114 puestos de votaci\u00f3n de las zonas rurales, impidiendo que comunidades rurales, campesina, afros y \u00e9tnicas se expresaran en las urnas en este departamento. Sin embargo, el respaldo popular a lo que significa el Pacto Hist\u00f3rico es incuestionable, al participar en esta consulta m\u00e1s de 66 mil votantes.<\/p>\n\n\n\n<p>Con este resultado se revalida que las bases del petrismo en el Cesar est\u00e1n firmes y decididas a continuar respaldando al gobierno del cambio, para seguir impulsando las grandes reformas y transformaciones que demanda el pueblo.<\/p>\n\n\n\n<p>En medio de la emoci\u00f3n y la satisfacci\u00f3n por el resultado obtenido, la segura candidata a la C\u00e1mara de Representantes por el Cesar, expres\u00f3 agradecimientos al pueblo cesarense \u201cpor confiar y creer en m\u00ed, en mi trabajo y dedicaci\u00f3n, en mi lucha por brindarle a las comunidades menos favorecidas oportunidades para construir un futuro digno y con justicia social\u201d.<\/p>\n\n\n\n<p>Pineda Ortiz se refiri\u00f3 de igual forma a lo que llam\u00f3 un sabotaje a la democracia por parte de la Registradur\u00eda, al negar la oportunidad a las comunidades que viven en la ruralidad de votar, ya que el traslado de 114 mesas de votaci\u00f3n a las cabeceras municipales, impidi\u00f3 que los votantes se movilizaran hasta los sitios dispuestos, principalmente por temas de recursos econ\u00f3micos.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Por \u00faltimo, recalc\u00f3 que \u201cno valieron los ataques medi\u00e1ticos de que fui objeto, ni las amenazas, porque el pueblo la tiene clara y entendi\u00f3 que los enemigos solo buscan enlodar la gesti\u00f3n que se demuestra con creces, y debilitar un proceso que solo se ha construido para dignificar la vida de los cesarenses\u201d.<\/p>\n\n\n\n<p>&nbsp;Los grandes resultados en esta consulta tambi\u00e9n incluyeron al senador y precandidato presidencial Iv\u00e1n Cepeda quien gan\u00f3 de forma contundente la consulta, al sumar m\u00e1s de un mill\u00f3n 500 mil votos.<\/p>\n\n\n\n<p>La participaci\u00f3n electoral en esta consulta interna sobrepas\u00f3 los dos millones 600 mil votantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una victoria inobjetable se llev\u00f3 la precandidata progresista Alexandra Pineda Ortiz al lograr 28 mil votos en la consulta interna del Pacto Hist\u00f3rico que convoc\u00f3 al pueblo para escoger a quienes los representar\u00e1n en las elecciones del pr\u00f3ximo a\u00f1o. El triunfo se da en medio de reclamaciones m\u00e1s que v\u00e1lidas a la organizaci\u00f3n electoral que [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":16701,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-16700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/conexioncesar.com\/wp-content\/uploads\/2025\/10\/9D2E7AF7-2415-4AC5-B674-9FAA14B4AC87.jpeg","_links":{"self":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/16700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/comments?post=16700"}],"version-history":[{"count":1,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/16700\/revisions"}],"predecessor-version":[{"id":16702,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/16700\/revisions\/16702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/media\/16701"}],"wp:attachment":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/media?parent=16700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/categories?post=16700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/tags?post=16700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}