{"id":17493,"date":"2026-07-14T15:48:59","date_gmt":"2026-07-14T20:48:59","guid":{"rendered":"https:\/\/conexioncesar.com\/?p=17493"},"modified":"2026-07-14T15:49:00","modified_gmt":"2026-07-14T20:49:00","slug":"colombia-y-brasil-se-estrenan-en-el-para-tiro-con-arco-con-titulos-hemisfericos-en-valledupar-2026","status":"publish","type":"post","link":"https:\/\/conexioncesar.com\/index.php\/2026\/07\/14\/colombia-y-brasil-se-estrenan-en-el-para-tiro-con-arco-con-titulos-hemisfericos-en-valledupar-2026\/","title":{"rendered":"Colombia y Brasil se estrenan en el Para tiro con arco con t\u00edtulos hemisf\u00e9ricos en Valledupar 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Carlos Mario Jim\u00e9nez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la gramilla del Estadio Armando Maestre Pavajeau, Colombia fue la protagonista durante la apertura del calendario del Para tiro con arco en los Juegos Parasuramericanos Valledupar 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a una destacada actuaci\u00f3n, la \u2018Tricolor\u2019 se convirti\u00f3 en la delegaci\u00f3n m\u00e1s ganadora de la primera jornada al conquistar dos medallas de oro, una de plata y consolidarse como l\u00edder del medallero de la disciplina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre las 5:00 de la tarde, cuando el ocaso asomaba en la Capital Mundial del Vallenato, las finales correspondieron a las competencias por equipos mixtos en las modalidades de compuesto, recurvo y W1, reuniendo a las principales delegaciones del continente en una jornada marcada por la precisi\u00f3n y el alto nivel t\u00e9cnico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer triunfo para el pa\u00eds anfitri\u00f3n lleg\u00f3 en la modalidad de equipos mixtos, arco compuesto, 50 metros Open, donde Ariana Correa y Cristian David Correa Alvar\u00e1n se proclamaron campeones tras liderar la clasificaci\u00f3n final y otorgarle a Colombia el primer metal de oro del torneo. Brasil obtuvo la plata con Jane Karla Gogel y Reinaldo Vagner Charao Ferreira, mientras que Ecuador complet\u00f3 el podio con Diana Gonzabay Guaman y Joffre Javier Villavicencio Galecio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La segunda presea dorada colombiana lleg\u00f3 en recurvo de equipo mixto, gracias al trabajo conjunto de Maira Alejandra Mosquera Rocha y H\u00e9ctor Julio Ram\u00edrez, quienes aseguraron un nuevo t\u00edtulo para el pa\u00eds. Brasil volvi\u00f3 a ubicarse en la segunda posici\u00f3n con Fabiola Dergovics y Thiago Pinheiro da Silva, mientras que Per\u00fa consigui\u00f3 el bronce por intermedio de Daniela Cecilia Campos Marzano y Marco Antonio Huaytalla P\u00e9rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De las tres finales disputadas, la \u00fanica que escap\u00f3 al dominio colombiano fue la categor\u00eda W1 equipo mixto, exclusiva para deportistas con discapacidad en brazos y piernas. En esta prueba, Brasil alcanz\u00f3 el t\u00edtulo con Juliana Cristina Ferreira da Silva y Eugenio Santana Franco. Colombia volvi\u00f3 a subir al podio con la medalla de plata gracias a Angie Alejandra Alarc\u00f3n Moreno y Miguel \u00c1ngel Patarroyo Gonz\u00e1lez, mientras que Chile obtuvo el bronce con Mariela L\u00f3pez Carrasco y V\u00edctor Manuel Saiz Bocaz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este resultado, Colombia cerr\u00f3 la primera jornada del Para tiro con arco como la delegaci\u00f3n m\u00e1s exitosa, con dos medallas de oro y una de plata, seguida por Brasil, que sum\u00f3 un oro y dos platas, mientras que Ecuador, Per\u00fa y Chile obtuvieron una medalla de bronce cada uno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las competencias continuar\u00e1n en Valledupar 2026, este martes 14 de julio, a partir de las 8:30 de la ma\u00f1ana, con las pruebas individuales y finales que se jugar\u00e1n en el segundo d\u00eda de competencias, donde se entregar\u00e1n nuevamente medallas y se conocer\u00e1n a los campeones de la jornada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Carlos Mario Jim\u00e9nez En la gramilla del Estadio Armando Maestre Pavajeau, Colombia fue la protagonista durante la apertura del calendario del Para tiro con arco en los Juegos Parasuramericanos Valledupar 2026. Gracias a una destacada actuaci\u00f3n, la \u2018Tricolor\u2019 se convirti\u00f3 en la delegaci\u00f3n m\u00e1s ganadora de la primera jornada al conquistar dos medallas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17497,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[38,1],"tags":[],"class_list":["post-17493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-sin-categoria"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/conexioncesar.com\/wp-content\/uploads\/2026\/07\/paratiro-con-arco-1.jpeg","_links":{"self":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/17493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/comments?post=17493"}],"version-history":[{"count":1,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/17493\/revisions"}],"predecessor-version":[{"id":17494,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/posts\/17493\/revisions\/17494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/media\/17497"}],"wp:attachment":[{"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/media?parent=17493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/categories?post=17493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexioncesar.com\/index.php\/wp-json\/wp\/v2\/tags?post=17493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}